{"id":1324,"date":"2014-04-30T00:40:33","date_gmt":"2014-04-30T06:40:33","guid":{"rendered":"http:\/\/proyectum.wordpress.com\/?p=1324"},"modified":"2014-04-30T00:40:33","modified_gmt":"2014-04-30T06:40:33","slug":"los-riesgos-de-un-proyecto","status":"publish","type":"post","link":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/","title":{"rendered":"Los riesgos de un proyecto"},"content":{"rendered":"<p>El principal objetivo en la <strong>gesti\u00f3n de riesgos<\/strong> es saber identificar a tiempo un riesgo y aplicar la mejor estrategia para erradicarlo antes de que comience a repercutir en el <strong>cumplimiento de los objetivos<\/strong> del proyecto.<\/p>\n<p>El <strong>riesgo<\/strong> por si solo implica incertidumbre, no sabemos si ocurrir\u00e1 o no, mucho menos sabemos la <a href=\"http:\/\/proyectum.files.wordpress.com\/2014\/04\/proyectum-167.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/proyectum.files.wordpress.com\/2014\/04\/proyectum-167.jpg?w=290\" alt=\"Riesgos de un proyecto\" width=\"290\" height=\"300\" class=\"alignright size-medium wp-image-1331\" \/><\/a> magnitud exacta de las consecuencias que puede ocasionar en caso de que ocurra. Al <strong>iniciar un proyecto<\/strong> debemos realizar una lista con los <strong>posibles riesgos<\/strong> a los que nos podemos enfrentar, pero es importante llevar a lo largo del <strong>proyecto<\/strong> una estricta <strong>gesti\u00f3n de los riesgos<\/strong>, los cuales podemos clasificar de la siguiente forma:<\/p>\n<p><strong>Riesgos conocidos.<\/strong><\/p>\n<p>Una vez que se ha evaluado el <strong>proyecto<\/strong>, tomando en cuanto los objetivos a cumplir, los tiempos se\u00f1alados y la calidad del producto, son f\u00e1cilmente identificados y predecibles. Un claro ejemplo lo podemos encontrar al revisar los objetivos y darnos cuenta que debemos cumplir con el primer <strong>entregable del proyecto<\/strong> en una determinada fecha, cuando en dicha fecha a\u00fan se va a encontrar el <strong>proyecto<\/strong> en una fase de desarrollo.<\/p>\n<p>Es importante hacer un buen <strong>an\u00e1lisis de los requerimientos<\/strong>, as\u00ed como tambi\u00e9n una buena planeaci\u00f3n, realizar correctamente estas tareas nos va arrojar pr\u00e1cticamente en autom\u00e1tico una <strong>serie de riesgos<\/strong>, los cuales vamos a tener la ventaja de saber administrarlos al haberlos identificados desde el <strong>inicio del proyecto<\/strong>.<\/p>\n<p><strong>Riesgos predecibles.<\/strong><\/p>\n<p>Para poder identificar este <strong>tipo de riesgos<\/strong> es necesario recurrir a la <strong>experiencia de proyectos anteriores<\/strong>. Va a ser de gran utilidad contar con colaboradores experimentados que nos apoyen a identificar <strong>posibles riesgos<\/strong> que ellos identificar\u00e1n de acuerdo a su experiencia por la participaci\u00f3n en <strong>proyectos anteriores<\/strong>.<\/p>\n<p>Como <strong>l\u00edder de proyecto<\/strong>, es el momento adecuado para resaltar la experiencia e identificar este tipo de riesgos. Como ejemplo, de acuerdo a la experiencia se puede prever que no contaremos con todos los recursos solicitados para la fecha solicitada, un <strong>riesgo<\/strong> que sin duda afectar\u00e1 en el cronograma si no lo sabemos administrar.<\/p>\n<p><strong>Riesgos impredecibles.<\/strong><\/p>\n<p>Este <strong>tipo de riesgos<\/strong> son los m\u00e1s inciertos, pues sabemos que pueden ocurrir, pero es extremadamente dif\u00edcil identificarlos por adelantado. Un ejemplo pude ser un desastre natural que pueda ocurrir a lo largo del <strong>proyecto<\/strong> y que llegue a afectar las instalaciones donde se lleve a cabo el mismo. <\/p>\n<p>Para este tipo de riesgos la recomendaci\u00f3n es plantear los peores escenarios posibles y a partir de ah\u00ed crear estrategias que nos permitan adelantarnos a los <strong>riesgos<\/strong>. Como ejemplo, imaginemos que la oficina se pueda quedar toda una semana sin energ\u00eda el\u00e9ctrica, tal vez es un hecho poco probable pero \u00bfC\u00f3mo se podr\u00eda afrontar? Ser\u00eda bueno contemplar un lugar alterno para poder trabajar.<\/p>\n<p>Existen <strong>riesgos<\/strong> que se deben de correr, es decir, todos los <strong>riesgos<\/strong> representan una amenaza para cumplir los objetivos del proyecto pero hay que evaluar si el balance entre el posible da\u00f1o y la recompensa que se obtiene al asumirlos es positivo. Trabajar con computadoras desactualizadas puede ser un <strong>riesgo<\/strong>, no sabemos hasta cuando funcionar\u00e1n, pero si sabemos administrarlo, el beneficio de usarlas es mayor a esperar a que se adquieran nuevos equipos.   <\/p>\n<p><strong>Administrar riesgos<\/strong> es una tarea que exige mantenernos en todo momento alerta. No duden en <strong>compartir sus experiencias<\/strong> al trabajar con riesgos.<\/p>\n<p>Sobre el autor: <a href=\"http:\/\/about.me\/omargarcia\" TARGET=\"_blank\" rel=\"noopener noreferrer\">Omar Garc\u00eda<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El principal objetivo en la gesti\u00f3n de riesgos es saber identificar a tiempo un riesgo y aplicar la mejor estrategia para erradicarlo antes de que comience a repercutir en el cumplimiento de los objetivos del proyecto. El riesgo por si solo implica incertidumbre, no sabemos si ocurrir\u00e1 o no, mucho menos sabemos la magnitud exacta [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":8258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[57,55],"tags":[84,296,303],"class_list":["post-1324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-direccion-de-proyectos","category-liderazgo","tag-administracion-de-proyectos","tag-administracion-de-riesgos","tag-riesgos-en-un-proyecto"],"acf":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los riesgos de un proyecto - Proyectum<\/title>\n<meta name=\"description\" content=\"El principal objetivo en la gesti\u00f3n de riesgos es saber identificar a tiempo un riesgo y aplicar la mejor estrategia para erradicarlo antes de que\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los riesgos de un proyecto - Proyectum\" \/>\n<meta property=\"og:description\" content=\"El principal objetivo en la gesti\u00f3n de riesgos es saber identificar a tiempo un riesgo y aplicar la mejor estrategia para erradicarlo antes de que\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyectum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proyectum\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-30T06:40:33+00:00\" \/>\n<meta name=\"author\" content=\"Omar Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@omarzgarcia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Omar Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/\"},\"author\":{\"name\":\"Omar Garc\u00eda\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/2c2f3285c31a3a005b11add8832ae8f7\"},\"headline\":\"Los riesgos de un proyecto\",\"datePublished\":\"2014-04-30T06:40:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"administraci\u00f3n de proyectos\",\"administraci\u00f3n de riesgos\",\"riesgos en un proyecto\"],\"articleSection\":[\"Direcci\u00f3n de Proyectos\",\"Liderazgo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/\",\"name\":\"Los riesgos de un proyecto - Proyectum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2014-04-30T06:40:33+00:00\",\"description\":\"El principal objetivo en la gesti\u00f3n de riesgos es saber identificar a tiempo un riesgo y aplicar la mejor estrategia para erradicarlo antes de que\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/los-riesgos-de-un-proyecto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los riesgos de un proyecto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"name\":\"Proyectum\",\"description\":\"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles\",\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\",\"name\":\"Proyectum\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"contentUrl\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"width\":600,\"height\":315,\"caption\":\"Proyectum\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proyectum\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sistemaproyectum\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCljouWimyhK_cNcC2jniUgw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/2c2f3285c31a3a005b11add8832ae8f7\",\"name\":\"Omar Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"caption\":\"Omar Garc\u00eda\"},\"description\":\"Creador de contenidos en Proyectum. Para seguir la conversaci\u00f3n puedes escribirme en: @omarzgarcia\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/@omarzgarcia\"],\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/author\\\/omarzgarcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los riesgos de un proyecto - Proyectum","description":"El principal objetivo en la gesti\u00f3n de riesgos es saber identificar a tiempo un riesgo y aplicar la mejor estrategia para erradicarlo antes de que","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/","og_locale":"es_ES","og_type":"article","og_title":"Los riesgos de un proyecto - Proyectum","og_description":"El principal objetivo en la gesti\u00f3n de riesgos es saber identificar a tiempo un riesgo y aplicar la mejor estrategia para erradicarlo antes de que","og_url":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/","og_site_name":"Proyectum","article_publisher":"https:\/\/www.facebook.com\/proyectum\/","article_published_time":"2014-04-30T06:40:33+00:00","author":"Omar Garc\u00eda","twitter_card":"summary_large_image","twitter_creator":"@omarzgarcia","twitter_misc":{"Escrito por":"Omar Garc\u00eda","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/#article","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/"},"author":{"name":"Omar Garc\u00eda","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/2c2f3285c31a3a005b11add8832ae8f7"},"headline":"Los riesgos de un proyecto","datePublished":"2014-04-30T06:40:33+00:00","mainEntityOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/#primaryimage"},"thumbnailUrl":"","keywords":["administraci\u00f3n de proyectos","administraci\u00f3n de riesgos","riesgos en un proyecto"],"articleSection":["Direcci\u00f3n de Proyectos","Liderazgo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/","url":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/","name":"Los riesgos de un proyecto - Proyectum","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/#primaryimage"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/#primaryimage"},"thumbnailUrl":"","datePublished":"2014-04-30T06:40:33+00:00","description":"El principal objetivo en la gesti\u00f3n de riesgos es saber identificar a tiempo un riesgo y aplicar la mejor estrategia para erradicarlo antes de que","breadcrumb":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/proyectum.com\/sistema\/blog\/los-riesgos-de-un-proyecto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proyectum.com\/sistema\/"},{"@type":"ListItem","position":2,"name":"Los riesgos de un proyecto"}]},{"@type":"WebSite","@id":"https:\/\/proyectum.com\/sistema\/#website","url":"https:\/\/proyectum.com\/sistema\/","name":"Proyectum","description":"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles","publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyectum.com\/sistema\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/proyectum.com\/sistema\/#organization","name":"Proyectum","url":"https:\/\/proyectum.com\/sistema\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/","url":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","contentUrl":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","width":600,"height":315,"caption":"Proyectum"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proyectum\/","https:\/\/www.linkedin.com\/company\/sistemaproyectum\/","https:\/\/www.youtube.com\/channel\/UCljouWimyhK_cNcC2jniUgw"]},{"@type":"Person","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/2c2f3285c31a3a005b11add8832ae8f7","name":"Omar Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","caption":"Omar Garc\u00eda"},"description":"Creador de contenidos en Proyectum. Para seguir la conversaci\u00f3n puedes escribirme en: @omarzgarcia","sameAs":["https:\/\/x.com\/@omarzgarcia"],"url":"https:\/\/proyectum.com\/sistema\/author\/omarzgarcia\/"}]}},"_links":{"self":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/1324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/comments?post=1324"}],"version-history":[{"count":0,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/1324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media?parent=1324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/categories?post=1324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/tags?post=1324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}