{"id":1639,"date":"2015-03-11T06:00:58","date_gmt":"2015-03-11T12:00:58","guid":{"rendered":"https:\/\/proyectum.wordpress.com\/?p=1639"},"modified":"2015-03-11T06:00:58","modified_gmt":"2015-03-11T12:00:58","slug":"el-mito-de-que-las-mujeres-lo-pueden-hacer-todo","status":"publish","type":"post","link":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/","title":{"rendered":"El mito de que las mujeres lo pueden hacer todo"},"content":{"rendered":"<p>Tal vez no todos lo hemos dicho, pero seguramente muchos lo hemos tenido en mente: \u201c<strong>Las mujeres lo pueden hacer todo<\/strong>\u201d. Saben <strong>equilibrar su vida profesional y personal<\/strong>, con la carga de trabajo que cada una conlleva.<\/p>\n<p><a href=\"https:\/\/proyectum.files.wordpress.com\/2015\/03\/mito-mujeres.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proyectum.files.wordpress.com\/2015\/03\/mito-mujeres.jpg\" alt=\"mito mujeres\" width=\"560\" height=\"265\" class=\"aligncenter size-full wp-image-1653\" \/><\/a><\/p>\n<p>Al pensar esto, o peor a\u00fan, cuando le expresamos esto a una compa\u00f1era, amiga o pareja, seguramente lo decimos como un gesto de admiraci\u00f3n, incluso quien reciba esta especie de \u201c<strong>halago<\/strong>\u201d, a simple vista lo tomar\u00e1 como un reconocimiento por el esfuerzo que realiza, pero lo m\u00e1s seguro es que en su interior, incluso de manera inconsciente, se sienta aun m\u00e1s <strong>presionada por las expectativas<\/strong> que se tienen de ella.<\/p>\n<p>Suceden dos cosas curiosas, por un lado se les ha hecho creer a las mujeres que son una especie de <strong>seres extra normales que pueden hacerlo todo<\/strong>, esto deriva en una exigencia que es mucho mayor a la que un hombre puede recibir. Por otro lado, a pesar de que s\u00ed, sin duda las mujeres hacen cosas extraordinarias y tienen que lidiar muchas veces con el hogar y el trabajo, muchas de ellas sufren el <strong>s\u00edndrome del impostor<\/strong>, que de manera muy reducida consiste en sentirse como fraudes a pesar de ser completamente capaces y juzgan su propio rendimiento como peor de lo que es en realidad.<\/p>\n<p>Resumiendo lo anterior, muchas mujeres tienen una lucha interna con ellas mismas <strong>por sentir que en realidad no lo pueden hacer todo<\/strong>.<\/p>\n<p>Como menciona <strong>Sheryl Sandberg<\/strong>, directora de operaciones de <strong>Facebook<\/strong>, en su libro <strong>Lean In<\/strong>: \u201c<em>Comparamos nuestros esfuerzos en el trabajo con los de nuestros colegas, generalmente hombres, que normalmente tienen muchas menos responsabilidades dentro del hogar. Y a continuaci\u00f3n comparamos nuestros esfuerzos en el hogar con las madres que no trabajan fuera y se dedican exclusivamente a sus familias.<\/em>\u201d<\/p>\n<p>Las mujeres hacen cosas extraordinarias, eso no hay ni la menor duda, pero como sociedad, les seguimos cargando la mano de m\u00e1s, ejerciendo una presi\u00f3n sobre ellas que no las permite <strong>sentirse plenas y satisfechas<\/strong>.<\/p>\n<p>En las parejas, aun siguen siendo muy pocos los hombres que se involucran en las tareas del hogar, dejando toda esta <strong>carga de trabajo a las mujeres<\/strong>. Como sociedad, vemos con naturalidad que una mujer se dedique a trabajar por completo al cuidado del hogar y en caso de ser una mujer que sale a trabajar, tambi\u00e9n nos parece natural que tenga que dividirse <strong>entre las labores del hogar y las de la oficina<\/strong>.<\/p>\n<p>Como ejemplo claro, cuando una mujer de \u00e9xito sobresale en su carrera profesional, es com\u00fan que reciba la siguiente pregunta o alguna similar: \u00bf<strong>C\u00f3mo logras equilibrar tu hogar y tu profesi\u00f3n<\/strong>? Una pregunta que jam\u00e1s recibir\u00e1 un hombre.<\/p>\n<p>Hombres, debemos asumir una mayor responsabilidad en tareas que por tradici\u00f3n se sigue creyendo que son exclusivas de las mujeres, como el cuidado de los hijos y las labores del hogar.<\/p>\n<p>Mujeres, <strong>son seres excepcionales<\/strong>, no podemos ni debemos exigirles m\u00e1s. Si\u00e9ntanse satisfechas por hacer todo lo que hacen pero vivan plenas, sin sentirse con <strong>la obligaci\u00f3n de que lo tienen que hacer todo<\/strong>.<\/p>\n<p>Sobre el autor: <a href=\"http:\/\/about.me\/omargarcia\" TARGET=\"_blank\" rel=\"noopener noreferrer\">Omar Garc\u00eda<\/a><\/p>\n<p><a href=\"http:\/\/tenstep.mx\/registro-proyectum.html\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proyectum.files.wordpress.com\/2015\/01\/suscribete.jpg?w=300\" alt=\"Suscribete Proyectum\" width=\"300\" height=\"75\" class=\"aligncenter size-medium wp-image-1548\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tal vez no todos lo hemos dicho, pero seguramente muchos lo hemos tenido en mente: \u201cLas mujeres lo pueden hacer todo\u201d. Saben equilibrar su vida profesional y personal, con la carga de trabajo que cada una conlleva. Al pensar esto, o peor a\u00fan, cuando le expresamos esto a una compa\u00f1era, amiga o pareja, seguramente lo [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":8258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[62],"tags":[],"class_list":["post-1639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexiones"],"acf":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El mito de que las mujeres lo pueden hacer todo - Proyectum<\/title>\n<meta name=\"description\" content=\"Tal vez no todos lo hemos dicho, pero seguramente muchos lo hemos tenido en mente: \u201cLas mujeres lo pueden hacer todo\u201d. Saben equilibrar su vida\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mito de que las mujeres lo pueden hacer todo - Proyectum\" \/>\n<meta property=\"og:description\" content=\"Tal vez no todos lo hemos dicho, pero seguramente muchos lo hemos tenido en mente: \u201cLas mujeres lo pueden hacer todo\u201d. Saben equilibrar su vida\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyectum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proyectum\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-11T12:00:58+00:00\" \/>\n<meta name=\"author\" content=\"Omar Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@omarzgarcia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Omar Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/\"},\"author\":{\"name\":\"Omar Garc\u00eda\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/2c2f3285c31a3a005b11add8832ae8f7\"},\"headline\":\"El mito de que las mujeres lo pueden hacer todo\",\"datePublished\":\"2015-03-11T12:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/\"},\"wordCount\":540,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Reflexiones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/\",\"name\":\"El mito de que las mujeres lo pueden hacer todo - Proyectum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2015-03-11T12:00:58+00:00\",\"description\":\"Tal vez no todos lo hemos dicho, pero seguramente muchos lo hemos tenido en mente: \u201cLas mujeres lo pueden hacer todo\u201d. Saben equilibrar su vida\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mito de que las mujeres lo pueden hacer todo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"name\":\"Proyectum\",\"description\":\"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles\",\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\",\"name\":\"Proyectum\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"contentUrl\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"width\":600,\"height\":315,\"caption\":\"Proyectum\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proyectum\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sistemaproyectum\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCljouWimyhK_cNcC2jniUgw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/2c2f3285c31a3a005b11add8832ae8f7\",\"name\":\"Omar Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"caption\":\"Omar Garc\u00eda\"},\"description\":\"Creador de contenidos en Proyectum. Para seguir la conversaci\u00f3n puedes escribirme en: @omarzgarcia\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/@omarzgarcia\"],\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/author\\\/omarzgarcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mito de que las mujeres lo pueden hacer todo - Proyectum","description":"Tal vez no todos lo hemos dicho, pero seguramente muchos lo hemos tenido en mente: \u201cLas mujeres lo pueden hacer todo\u201d. Saben equilibrar su vida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/","og_locale":"es_ES","og_type":"article","og_title":"El mito de que las mujeres lo pueden hacer todo - Proyectum","og_description":"Tal vez no todos lo hemos dicho, pero seguramente muchos lo hemos tenido en mente: \u201cLas mujeres lo pueden hacer todo\u201d. Saben equilibrar su vida","og_url":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/","og_site_name":"Proyectum","article_publisher":"https:\/\/www.facebook.com\/proyectum\/","article_published_time":"2015-03-11T12:00:58+00:00","author":"Omar Garc\u00eda","twitter_card":"summary_large_image","twitter_creator":"@omarzgarcia","twitter_misc":{"Escrito por":"Omar Garc\u00eda","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/#article","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/"},"author":{"name":"Omar Garc\u00eda","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/2c2f3285c31a3a005b11add8832ae8f7"},"headline":"El mito de que las mujeres lo pueden hacer todo","datePublished":"2015-03-11T12:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/"},"wordCount":540,"commentCount":0,"publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/#primaryimage"},"thumbnailUrl":"","articleSection":["Reflexiones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/","url":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/","name":"El mito de que las mujeres lo pueden hacer todo - Proyectum","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/#primaryimage"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/#primaryimage"},"thumbnailUrl":"","datePublished":"2015-03-11T12:00:58+00:00","description":"Tal vez no todos lo hemos dicho, pero seguramente muchos lo hemos tenido en mente: \u201cLas mujeres lo pueden hacer todo\u201d. Saben equilibrar su vida","breadcrumb":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/proyectum.com\/sistema\/blog\/el-mito-de-que-las-mujeres-lo-pueden-hacer-todo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proyectum.com\/sistema\/"},{"@type":"ListItem","position":2,"name":"El mito de que las mujeres lo pueden hacer todo"}]},{"@type":"WebSite","@id":"https:\/\/proyectum.com\/sistema\/#website","url":"https:\/\/proyectum.com\/sistema\/","name":"Proyectum","description":"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles","publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyectum.com\/sistema\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/proyectum.com\/sistema\/#organization","name":"Proyectum","url":"https:\/\/proyectum.com\/sistema\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/","url":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","contentUrl":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","width":600,"height":315,"caption":"Proyectum"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proyectum\/","https:\/\/www.linkedin.com\/company\/sistemaproyectum\/","https:\/\/www.youtube.com\/channel\/UCljouWimyhK_cNcC2jniUgw"]},{"@type":"Person","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/2c2f3285c31a3a005b11add8832ae8f7","name":"Omar Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","caption":"Omar Garc\u00eda"},"description":"Creador de contenidos en Proyectum. Para seguir la conversaci\u00f3n puedes escribirme en: @omarzgarcia","sameAs":["https:\/\/x.com\/@omarzgarcia"],"url":"https:\/\/proyectum.com\/sistema\/author\/omarzgarcia\/"}]}},"_links":{"self":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/1639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/comments?post=1639"}],"version-history":[{"count":0,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/1639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media?parent=1639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/categories?post=1639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/tags?post=1639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}