{"id":3541,"date":"2017-10-27T10:00:35","date_gmt":"2017-10-27T15:00:35","guid":{"rendered":"http:\/\/www.proyectum.lat\/?p=3541"},"modified":"2017-10-27T10:00:35","modified_gmt":"2017-10-27T15:00:35","slug":"el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios","status":"publish","type":"post","link":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/","title":{"rendered":"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios"},"content":{"rendered":"<p>\u201c<em>La confianza es el pegamento de la vida.<br \/>\nEs el ingrediente m\u00e1s esencial para una comunicaci\u00f3n efectiva.<br \/>\nEs el principio fundamental que mantiene todas las relaciones<\/em>\u201d.- <strong>Stephen Covey<\/strong><\/p>\n<p>Durante m\u00e1s de 10 a\u00f1os he estado involucrado con diversas organizaciones profesionales. Con algunas de ellas mi participaci\u00f3n ha sido muy activa, con algunas otras, he mantenido un perfil m\u00e1s discreto. M\u00e1s all\u00e1 de mi participaci\u00f3n activa o no, en todos esos a\u00f1os, he aprendido que un importante activo que tienes como profesional es tu red de contactos. <\/p>\n<p>Pero, \u00bf<strong>Qu\u00e9 hacer para ampliar tu red de contactos<\/strong>? \u00bfC\u00f3mo te puedes relacionar activamente de manera que incrementes tus posibilidades de hacer negocios? <\/p>\n<p>A trav\u00e9s de los a\u00f1os, desarrollar esta habilidad me ha permitido, literalmente, trabajar con mis \u00eddolos. Gracias a esta habilidad, he tenido la oportunidad y la gran satisfacci\u00f3n de conocer, interactuar, trabajar y aprender en conjunto con personalidades que han dejado huella en este mundo por sus destacad\u00edsimas aportaciones. <\/p>\n<p>El <strong>networking es una habilidad<\/strong> que te ayuda a <strong>crear, mantener y ampliar tu red profesional<\/strong> de contactos, con el fin de dar a conocer a tu negocio o a ti como profesional, adem\u00e1s ayuda a desarrollar habilidades importantes como dialogar, mantener concentraci\u00f3n, escuchar activamente y aprender de los dem\u00e1s, otra ventaja es que puedes encontrar colaboradores, socios o incluso posibles inversionistas.<\/p>\n<p>A trav\u00e9s del <strong>networking<\/strong> posibilitas el intercambio de informaci\u00f3n y contactos, as\u00ed como el establecimiento de relaciones significativas con personas que comparten intereses profesionales comunes. As\u00ed que, a trav\u00e9s de esta habilidad puedes avanzar en tu carrera, expandir tu negocio, aumentar tu visibilidad y mejorar tu red de contactos comerciales para crear las posibilidades de generar m\u00e1s negocios. <\/p>\n<blockquote><p>\n<em>Lo primero que tienes que tomar en cuenta es que <strong>tu tarjeta de presentaci\u00f3n no es obligatoria<\/strong>. El mayor \u00e9xito de las redes proviene de la construcci\u00f3n de relaciones reales y de confianza.<\/em><\/p><\/blockquote>\n<p>Llegas solo, tu coraz\u00f3n late un poco m\u00e1s r\u00e1pido de lo normal y de repente todo tu carisma y encanto se esfuman. Intentas establecer contacto visual con alguien para tratar de encontrar un hogar temporal y seguro en lo que puede parecer un mar de extra\u00f1os, pero todos se ven felices conversando.<\/p>\n<p>Si bien esto puede sonar como tu experiencia en un baile de la escuela secundaria, tambi\u00e9n es lo que muchas personas sienten cuando entran en un <strong>evento de networking<\/strong>. Estas son reacciones completamente naturales, incluso para los m\u00e1s extrovertidos. La gran noticia es que la gente va a estos eventos para conocer extra\u00f1os, por lo que est\u00e1s en la misma posici\u00f3n que todos los dem\u00e1s. <\/p>\n<p><strong>Tu actitud hace la diferencia<\/strong>. Al principio te vas a sentir un poco raro al acercarte a alg\u00fan extra\u00f1o y tratar de entablar una conversaci\u00f3n de la nada. Pero son condiciones sine-qua-non para poder hacer <strong>networking<\/strong>, dejar a un lado tu timidez y miedo al rechazo. Si sabes que vas a asistir a un evento profesional, congreso, seminario, curso o algo parecido, mental\u00edzate, y prep\u00e1rate revisando los consejos que comparto m\u00e1s abajo, estoy seguro que siguiendo solo algunos de ellos, tendr\u00e1s mejores resultados. <\/p>\n<p>Producto de algunas lecturas y de mi reflexi\u00f3n personal, aqu\u00ed comparto una recopilaci\u00f3n de <strong>20 consejos \u00fatiles para transitar en un evento de networking y no morir en el intento<\/strong>.<\/p>\n<p><strong>1.\tS\u00e9 t\u00fa mismo.<\/strong> Los eventos de networking se consideran puntos de partida para la construcci\u00f3n de relaciones. Si intentas proyectar algo que no eres, comenzar\u00e1s estas nuevas relaciones con una mentira. No trates de ser la persona que crees que otros quieren conocer. S\u00e9 genuino. Las personas con las que te conectas cuando eres aut\u00e9ntico son aquellas con las que querr\u00e1s mantenerte en contacto.<\/p>\n<p><strong>2.\tPres\u00e9ntate con el organizador.<\/strong> Una excelente manera de conocer m\u00e1s acerca de una organizaci\u00f3n y de qui\u00e9n est\u00e1 involucrado, es buscar el organizador del evento y presentarte. \u00c9l te puede orientar en la direcci\u00f3n correcta y puede presentarte a otros asistentes para que arranques con el pie derecho. <\/p>\n<p><strong>3.\tEstablece expectativas razonables.<\/strong> Cuando asistas a un evento, ten claro por qu\u00e9 est\u00e1s ah\u00ed.  \u00bfTu objetivo es entrar en contacto con una nueva organizaci\u00f3n y sentir la vibra y conocer el ambiente? \u00bfEst\u00e1s ah\u00ed para conocer a cinco nuevas personas? \u00bfEst\u00e1s para conocer a una o dos personas espec\u00edficas? Todas estas son expectativas razonables. <\/p>\n<p><strong>4.\tPlanea previamente.<\/strong>  Para lograr cumplir tus expectativas, desarrolla un sencillo plan previo. Establece tus metas y objetivos en funci\u00f3n de tus intereses. Planea tus conversaciones, desarrolla una introducci\u00f3n breve, trata de crear una, dos o tres frases de alto impacto que te permitan despertar el inter\u00e9s de tus interlocutores y que te ayuden a romper la barrera inicial. Ensaya enfrente del espejo, visual\u00edzate haci\u00e9ndolo. Esto ayudar\u00e1 a cumplir los objetivos que te has planteado. <\/p>\n<p><strong>5.\tS\u00e9 espec\u00edfico.<\/strong> En funci\u00f3n de tu plan, cuanto m\u00e1s espec\u00edfico puedas ser sobre lo que haces y lo que otros pueden hacer para ayudarte (si preguntan), mejor. Comenta los nombres de algunas compa\u00f1\u00edas espec\u00edficas con las que deseas trabajar. <\/p>\n<p><strong>6.\tPreg\u00fantate por qu\u00e9 les deber\u00eda importar.<\/strong> Considera por qu\u00e9 la persona con la que est\u00e1s hablando, debe preocuparse por lo que est\u00e1s diciendo. Dise\u00f1a tus conversaciones en consecuencia. Solo tienes un poco de tiempo para causar una buena impresi\u00f3n, as\u00ed que trata de hacerlo lo mejor posible. <\/p>\n<p><strong>7.\tHaz preguntas poderosas.<\/strong> La \u00fanica forma de conocer a otra persona es haciendo preguntas poderosas, genuinas y reflexivas. Siempre es mejor concluir una conversaci\u00f3n en donde hayas dejado que la otra persona hable m\u00e1s que t\u00fa. No solo se sentir\u00e1n bien con la conversaci\u00f3n, sino que tambi\u00e9n sabr\u00e1s mucho sobre ella, lo que te ayudar\u00e1 a planear y conducir un mejor seguimiento posteriormente. <\/p>\n<p><strong>8.\tCompartir es crecer.<\/strong> Esto no es menos cierto ahora que en el jard\u00edn de ni\u00f1os. Si est\u00e1s dispuesto a compartir tu conocimiento, tus contactos e incluso algunos de tus recursos, es m\u00e1s probable que otros te ayuden en reciprocidad. Desarrolla sinceramente tu naturaleza generosa, comparte sin esperar algo a cambio. La vida tiene extra\u00f1as formas de recompensar ese tipo de gestos.<\/p>\n<p><strong>9.\tSirve de puente.<\/strong> Si haces preguntas poderosas y consideras c\u00f3mo puedes ayudar a los dem\u00e1s, naturalmente comenzar\u00e1s a establecer conexiones entre las personas con las que est\u00e1s hablando y otras personas de tu red. \u00a1Ofrece hacer estas conexiones! Tal vez son dos personas que tienen los mismos clientes objetivo, o tal vez sepas que un contacto tuyo est\u00e1 buscando el servicio que brinda alguien que conoces. Anima a ambas partes a que se contacten posteriormente, que se re\u00fanan para que puedan explorar que puede surgir. Esto no solo te pagar\u00e1 dividendos, sino que tambi\u00e9n te ayudar\u00e1 a perfeccionar tus habilidades para hacer este tipo de contactos. <\/p>\n<p><strong>10.\tComprom\u00e9tete.<\/strong> Mant\u00e9n contacto visual con tu interlocutor. Mueve la cabeza e inclina tu cuerpo hacia \u00e9l cuando est\u00e9 hablando, genera rapport reflejando discretamente algunos de sus movimientos. Estas peque\u00f1as se\u00f1ales contribuyen en gran medida a hacer que se sientan como si te importara, lo que te ayuda a construir una buena relaci\u00f3n y confianza: la base sobre la que m\u00e1s tarde podr\u00e1s hacer negocios.<\/p>\n<p><strong>11.\tHigh Touch low tech.<\/strong> En los tiempos que estamos viviendo, cada vez se est\u00e1 perdiendo m\u00e1s el milenario arte de conversar. Es importante que te mantengas concentrado en tus objetivos. Deja de lado cualquier tipo de dispositivo electr\u00f3nico, pues solo ser\u00e1 un distractor y, si como yo, tienes el mal h\u00e1bito de \u201crevisar\u201d cada 40 segundos tu celular para ver si lleg\u00f3 alg\u00fan mensaje importante, esto solo puede crear una mala impresi\u00f3n en tus interlocutores. Busca crear una conversaci\u00f3n c\u00e1lida, sincera, mira a los ojos y muestra tu inteligencia olvid\u00e1ndote de tu dispositivo inteligente. <\/p>\n<p><strong>12.\tToma notas.<\/strong> Cuando solicites la tarjeta de alguien, despu\u00e9s de una buena conversaci\u00f3n, toma notas en su tarjeta de presentaci\u00f3n, despu\u00e9s de que se vayan o inmediatamente despu\u00e9s del evento. Esto te ayudar\u00e1 a ser m\u00e1s espec\u00edfico en tu seguimiento. <\/p>\n<p><strong>13.\tEncuentra la barra.<\/strong>   Ya sea que est\u00e9s bebiendo o no, siempre es una buena idea posicionarse en el borde de la barra. Muchas personas corren al bar cuando llegan a un evento de networking para obtener un breve respiro de una entrada abrumadora. Si te colocas a unos pasos de la barra, puedes entablar una conversaci\u00f3n f\u00e1cilmente mientras la gente se da vuelta con una bebida en la mano.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.proyectum.lat\/wp-content\/uploads\/2017\/10\/Barra-Networking-consejos.jpg\" alt=\"Barra Networking consejos\" width=\"985\" height=\"457\" class=\"aligncenter size-full wp-image-3556\" srcset=\"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Barra-Networking-consejos.jpg 985w, https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Barra-Networking-consejos-600x278.jpg 600w, https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Barra-Networking-consejos-768x356.jpg 768w, https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Barra-Networking-consejos-367x170.jpg 367w\" sizes=\"auto, (max-width: 985px) 100vw, 985px\" \/><\/p>\n<p><strong>14.\tTrata a las personas como amigos.<\/strong> \u00bfIr\u00edas con un amigo, interrumpir\u00edas su conversaci\u00f3n, entregar\u00edas una tarjeta de visita, hablar\u00edas de ti y luego te ir\u00edas? Por supuesto no. Trata a las nuevas relaciones como tratar\u00edas a tus amistades. Establece una buena relaci\u00f3n y conf\u00eda en que los negocios suceder\u00e1n.<\/p>\n<p><strong>15.\tNo te extiendas demasiado pues tu esfuerzo se diluye.<\/strong> Cuando participas en demasiados eventos donde nadie te conoce, te est\u00e1s haciendo un flaco servicio al tener que construir tu marca desde cero en cada ambiente. Tambi\u00e9n encontrar\u00e1s que las redes son mucho m\u00e1s divertidas cuando te conviertes en visitante habitual. La gente hablar\u00e1 de tus haza\u00f1as a los nuevos asistentes (esto siempre es mejor que hacerlo t\u00fa mismo) y ver\u00e1s muchas caras familiares.<\/p>\n<p><strong>16.\tConsidera la red extendida.<\/strong> Al conocer a las personas, es importante recordar que, incluso si no pueden ayudarte directamente, es probable que alguien en su red pueda hacerlo.<\/p>\n<p><strong>17.\tNo hagas dispendio de tarjetas.<\/strong> Lo m\u00e1s parecido a arrojar todas tus tarjetas de presentaci\u00f3n como confeti, eres t\u00fa, entregando tarjetas de presentaci\u00f3n a todas las personas que conozcas sin que te lo pidan. Si no has establecido una buena relaci\u00f3n con alguien para alentarlo a solicitar tu tarjeta, no la ofrezcas.<\/p>\n<p><strong>18.\tNO \u00abtrabajes la habitaci\u00f3n\u00bb.<\/strong> No intentes conocer a tantas personas como sea posible en el evento; conc\u00e9ntrate en establecer pocas conexiones, pero busca que sean s\u00f3lidas. Las personas pueden sentir cuando simplemente hablas con ellos para tomar su tarjeta e irte. Estas interacciones cortas no ser\u00e1n memorables y, por lo tanto, trabajar\u00e1n en tu contra. Intenta conocer a algunas personas y comenzar un di\u00e1logo significativo.<\/p>\n<p><strong>19.\tNo tengas miedo de unirte.<\/strong> No hay nada de malo en unirte a una conversaci\u00f3n y esperar un descanso natural en la conversaci\u00f3n para presentarte. En la mayor\u00eda de los casos, las personas que ya est\u00e1n hablando disfrutar\u00e1n de la interrupci\u00f3n porque les da la oportunidad de conocer a alguien nuevo. Si sientes que has entrado en una discusi\u00f3n seria, solo exc\u00fasate cort\u00e9smente y al\u00e9jate con discreci\u00f3n. <\/p>\n<p><strong>20.\tAl\u00e9jate de tus amigos.<\/strong> Si vas con un amigo o colega de trabajo a la sesi\u00f3n, lo peor que pueden hacer es ponerse a conversar entre ustedes. El networking no es una actividad meramente social. El establecer un acercamiento social es una plataforma para ampliar tu red de contactos y eventualmente poder hacer negocios. Esto no pasar\u00e1 si vas con amigos a platicar las an\u00e9cdotas de sus andanzas. As\u00ed que al\u00e9jate de tus amigos y al final comparen notas, vean a qu\u00e9 personas importantes conocieron, as\u00ed obtendr\u00e1n el m\u00e1ximo provecho de la reuni\u00f3n y esto seguramente les pagar\u00e1 dividendos en el futuro. <\/p>\n<p>Sigue todos o algunos de estos sencillos pasos y estar\u00e1s preparado para mejorar tu participaci\u00f3n <strong>en la pr\u00f3xima oportunidad que tengas de hacer networking<\/strong> y, con suerte, podr\u00e1s construir algunas relaciones significativas en el proceso. Y recuerda; contrario a lo que te ense\u00f1aron cuando eras ni\u00f1o, el mejor consejo en este caso, es, <strong>\u00a1habla con extra\u00f1os!<\/strong><\/p>\n<p>\u00bfY t\u00fa? \u00bfQue consejos podr\u00edas compartir para desarrollar esta habilidad?<\/p>\n<p>Autor: <strong>Jorge Vald\u00e9s Garciatorres<\/strong>, PMP, SMC.    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa confianza es el pegamento de la vida. Es el ingrediente m\u00e1s esencial para una comunicaci\u00f3n efectiva. Es el principio fundamental que mantiene todas las relaciones\u201d.- Stephen Covey Durante m\u00e1s de 10 a\u00f1os he estado involucrado con diversas organizaciones profesionales. Con algunas de ellas mi participaci\u00f3n ha sido muy activa, con algunas otras, he mantenido [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":3545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[67],"tags":[1913,1914,1915,1916,1917,1918,1919,1920,1921,1922,1923],"class_list":["post-3541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","tag-20-consejos-networking","tag-ampliar-tu-red-profesional","tag-consejos-ampliar-tu-red-profesional","tag-consejos-networking","tag-consejos-para-hacer-networking","tag-evento-de-networking","tag-networking","tag-networking-es-una-habilidad","tag-networking-y-no-morir-en-el-intento","tag-que-hacer-para-ampliar-tu-red-de-contactos","tag-tu-actitud-hace-la-diferencia"],"acf":[],"featured_image_src":{"landsacpe":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking-1140x445.jpg",1140,445,true],"list":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking-463x348.jpg",463,348,true],"medium":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking-300x155.jpg",300,155,true],"full":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking.jpg",1183,611,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios - Proyectum<\/title>\n<meta name=\"description\" content=\"\u201cLa confianza es el pegamento de la vida. Es el ingrediente m\u00e1s esencial para una comunicaci\u00f3n efectiva. Es el principio fundamental que mantiene todas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios - Proyectum\" \/>\n<meta property=\"og:description\" content=\"\u201cLa confianza es el pegamento de la vida. Es el ingrediente m\u00e1s esencial para una comunicaci\u00f3n efectiva. Es el principio fundamental que mantiene todas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyectum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proyectum\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-27T15:00:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1183\" \/>\n\t<meta property=\"og:image:height\" content=\"611\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Vald\u00e9s Garciatorres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Vald\u00e9s Garciatorres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/\"},\"author\":{\"name\":\"Jorge Vald\u00e9s Garciatorres\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/d31dc858cdc64bb094f97de74c958a16\"},\"headline\":\"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios\",\"datePublished\":\"2017-10-27T15:00:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/\"},\"wordCount\":2050,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Recomendaciones-Networking.jpg\",\"keywords\":[\"20 consejos networking\",\"ampliar tu red profesional\",\"consejos ampliar tu red profesional\",\"consejos networking\",\"consejos para hacer networking\",\"evento de networking\",\"networking\",\"networking es una habilidad\",\"networking y no morir en el intento\",\"Qu\u00e9 hacer para ampliar tu red de contactos\",\"Tu actitud hace la diferencia\"],\"articleSection\":[\"Comunicaci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/\",\"name\":\"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios - Proyectum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Recomendaciones-Networking.jpg\",\"datePublished\":\"2017-10-27T15:00:35+00:00\",\"description\":\"\u201cLa confianza es el pegamento de la vida. Es el ingrediente m\u00e1s esencial para una comunicaci\u00f3n efectiva. Es el principio fundamental que mantiene todas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Recomendaciones-Networking.jpg\",\"contentUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/Recomendaciones-Networking.jpg\",\"width\":1183,\"height\":611,\"caption\":\"Recomendaciones Networking\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"name\":\"Proyectum\",\"description\":\"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles\",\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\",\"name\":\"Proyectum\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"contentUrl\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"width\":600,\"height\":315,\"caption\":\"Proyectum\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proyectum\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sistemaproyectum\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCljouWimyhK_cNcC2jniUgw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/d31dc858cdc64bb094f97de74c958a16\",\"name\":\"Jorge Vald\u00e9s Garciatorres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g\",\"caption\":\"Jorge Vald\u00e9s Garciatorres\"},\"description\":\"Jorge es autor del libro \\\"El Camino hacia la PMO \u00c1gil\\\". Es Coautor de un modelo sist\u00e9mico para la evaluaci\u00f3n y mejora del Ecosistema Organizacional de Direcci\u00f3n de de Proyectos. Ha sido consultor, instructor y facilitador desde 2005 en temas relacionados con Estrategia, Direcci\u00f3n de Proyectos y Optimizaci\u00f3n de Procesos de Negocio. Igualmente es contador de historias y frecuentemente participa en diversos foros, compartiendo sus reflexiones. Jorge es miembro de importantes organizaciones como el PMI y el NTL Institute. Adem\u00e1s, cuenta con varias certificaciones como la de PMP, Systems Thinking, Agile Leadership, entre muchas otras.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jorgevaldex\\\/\"],\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/author\\\/jvaldex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios - Proyectum","description":"\u201cLa confianza es el pegamento de la vida. Es el ingrediente m\u00e1s esencial para una comunicaci\u00f3n efectiva. Es el principio fundamental que mantiene todas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/","og_locale":"es_ES","og_type":"article","og_title":"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios - Proyectum","og_description":"\u201cLa confianza es el pegamento de la vida. Es el ingrediente m\u00e1s esencial para una comunicaci\u00f3n efectiva. Es el principio fundamental que mantiene todas","og_url":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/","og_site_name":"Proyectum","article_publisher":"https:\/\/www.facebook.com\/proyectum\/","article_published_time":"2017-10-27T15:00:35+00:00","og_image":[{"width":1183,"height":611,"url":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking.jpg","type":"image\/jpeg"}],"author":"Jorge Vald\u00e9s Garciatorres","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Vald\u00e9s Garciatorres","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/#article","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/"},"author":{"name":"Jorge Vald\u00e9s Garciatorres","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/d31dc858cdc64bb094f97de74c958a16"},"headline":"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios","datePublished":"2017-10-27T15:00:35+00:00","mainEntityOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/"},"wordCount":2050,"commentCount":0,"publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/#primaryimage"},"thumbnailUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking.jpg","keywords":["20 consejos networking","ampliar tu red profesional","consejos ampliar tu red profesional","consejos networking","consejos para hacer networking","evento de networking","networking","networking es una habilidad","networking y no morir en el intento","Qu\u00e9 hacer para ampliar tu red de contactos","Tu actitud hace la diferencia"],"articleSection":["Comunicaci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/","url":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/","name":"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios - Proyectum","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/#primaryimage"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/#primaryimage"},"thumbnailUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking.jpg","datePublished":"2017-10-27T15:00:35+00:00","description":"\u201cLa confianza es el pegamento de la vida. Es el ingrediente m\u00e1s esencial para una comunicaci\u00f3n efectiva. Es el principio fundamental que mantiene todas","breadcrumb":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/#primaryimage","url":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking.jpg","contentUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2017\/10\/Recomendaciones-Networking.jpg","width":1183,"height":611,"caption":"Recomendaciones Networking"},{"@type":"BreadcrumbList","@id":"https:\/\/proyectum.com\/sistema\/blog\/el-arte-de-hacer-networking-20-consejos-para-desarrollar-relaciones-significativas-de-negocios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proyectum.com\/sistema\/"},{"@type":"ListItem","position":2,"name":"El arte de hacer Networking: 20 consejos para desarrollar relaciones significativas de negocios"}]},{"@type":"WebSite","@id":"https:\/\/proyectum.com\/sistema\/#website","url":"https:\/\/proyectum.com\/sistema\/","name":"Proyectum","description":"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles","publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyectum.com\/sistema\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/proyectum.com\/sistema\/#organization","name":"Proyectum","url":"https:\/\/proyectum.com\/sistema\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/","url":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","contentUrl":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","width":600,"height":315,"caption":"Proyectum"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proyectum\/","https:\/\/www.linkedin.com\/company\/sistemaproyectum\/","https:\/\/www.youtube.com\/channel\/UCljouWimyhK_cNcC2jniUgw"]},{"@type":"Person","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/d31dc858cdc64bb094f97de74c958a16","name":"Jorge Vald\u00e9s Garciatorres","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g","caption":"Jorge Vald\u00e9s Garciatorres"},"description":"Jorge es autor del libro \"El Camino hacia la PMO \u00c1gil\". Es Coautor de un modelo sist\u00e9mico para la evaluaci\u00f3n y mejora del Ecosistema Organizacional de Direcci\u00f3n de de Proyectos. Ha sido consultor, instructor y facilitador desde 2005 en temas relacionados con Estrategia, Direcci\u00f3n de Proyectos y Optimizaci\u00f3n de Procesos de Negocio. Igualmente es contador de historias y frecuentemente participa en diversos foros, compartiendo sus reflexiones. Jorge es miembro de importantes organizaciones como el PMI y el NTL Institute. Adem\u00e1s, cuenta con varias certificaciones como la de PMP, Systems Thinking, Agile Leadership, entre muchas otras.","sameAs":["https:\/\/www.linkedin.com\/in\/jorgevaldex\/"],"url":"https:\/\/proyectum.com\/sistema\/author\/jvaldex\/"}]}},"_links":{"self":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/3541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/comments?post=3541"}],"version-history":[{"count":0,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/3541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media\/3545"}],"wp:attachment":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media?parent=3541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/categories?post=3541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/tags?post=3541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}