{"id":5115,"date":"2019-05-15T13:30:56","date_gmt":"2019-05-15T18:30:56","guid":{"rendered":"http:\/\/www.proyectum.lat\/?p=5115"},"modified":"2019-05-15T13:30:56","modified_gmt":"2019-05-15T18:30:56","slug":"cuidando-el-capital-humano-empresas-saludables","status":"publish","type":"post","link":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/","title":{"rendered":"Cuidando el capital humano, empresas saludables"},"content":{"rendered":"\n<p>Por: <strong>Ivette Rosales Herrera<\/strong>. <\/p>\n\n\n\n<p style=\"text-align:right\"><em>\u201cLa fortaleza del equipo est\u00e1 en cada miembro por separado. <\/em><\/p>\n\n\n\n<p style=\"text-align:right\"><em>La fortaleza de cada miembro es el equipo\u201d<\/em>. <strong>Phil Jackson <\/strong><\/p>\n\n\n\n<p>Dentro de una empresa <strong>el eslab\u00f3n m\u00e1s importante es el personal<\/strong> y muchas veces puede verse afectado por el <strong>estr\u00e9s laboral<\/strong>. Hoy en d\u00eda es muy com\u00fan escuchar que alguien sufre de esta enfermedad y aunque esto suena extra\u00f1o, puede ser m\u00e1s real de lo que parece. <\/p>\n\n\n\n<p>Seg\u00fan cifras de la Organizaci\u00f3n Mundial de la Salud, se estima que cada a\u00f1o surgen 160 millones de nuevos casos de <strong>enfermedades relacionadas al trabajo<\/strong>, dadas las condiciones en que se labora, genera que un tercio de ellos presenten dolor de espalda, un 16% perdida de la audici\u00f3n, un 10% c\u00e1ncer de pulm\u00f3n y un 8% depresi\u00f3n atribuida a los riesgos de trabajo; todos estos datos son realmente alarmantes, ya que no solo est\u00e1 en riesgo la persona sino <strong>la trayectoria de nuestra empresa<\/strong>.&nbsp; Las consecuencias de un mal \u00e1mbito laboral pueden ir desde el <strong>absentismo y la insatisfacci\u00f3n del empleado<\/strong>, hasta el decrecimiento de calidad en los procesos o productos o una <strong>mala atenci\u00f3n al cliente<\/strong>, llev\u00e1ndonos sin duda a una p\u00e9rdida econ\u00f3mica.&nbsp; <\/p>\n\n\n\n<p>Al momento de escuchar el t\u00e9rmino \u201c<strong>empresa saludable<\/strong>\u201d, podemos pensar que est\u00e1 relacionada con la promoci\u00f3n del consumo de productos que benefician nuestra salud, como dietas o rutinas de ejercicios, aunque no es realmente de lo que se trata.&nbsp; Una <strong>empresa saludable<\/strong> es aquella que no solo se preocupa por la salud f\u00edsica y emocional de sus empleados, sino que se ocupa de ello, creando as\u00ed un espacio laboral saludable cumpliendo con la legislaci\u00f3n de Seguridad y Salud, siendo consciente de la importancia y el valor que aporta el bienestar del personal. &nbsp;Por lo tanto el bienestar de los trabajadores impacta fuertemente en la habilidad de la empresa para realizar sus funciones, y as\u00ed poder alcanzar su visi\u00f3n y misi\u00f3n, naturalmente, los empleados altamente productivos contribuir\u00e1n a la competitividad de la empresa. <\/p>\n\n\n\n<p>Adem\u00e1s de tener empleados m\u00e1s sanos y motivados, algunas caracter\u00edsticas de las Empresas saludables son: el <strong>fomentar el sentido de pertenencia<\/strong> a la empresa, mostrar una buena imagen corporativa y la m\u00e1s importante, detectar, implementar e incorporar a los empleados en un plan preventivo de salud.&nbsp; <\/p>\n\n\n\n<p>En los \u00faltimos a\u00f1os alrededor del mundo las empresas se han esforzado por ser <strong>organizaciones saludables<\/strong> y han puesto en marcha programas de salud y bienestar. <\/p>\n\n\n\n<p>Un ejemplo a nivel mundial es <strong>Microsoft<\/strong>, que para cuidar el bienestar de sus empleados implement\u00f3 horarios de trabajo flexibles, abonos al gimnasio, servicios como tintorer\u00eda, fisioterapeuta, taller de autom\u00f3vil, recitales o spa org\u00e1nico. <\/p>\n\n\n\n<p>En M\u00e9xico muchas empresas han optado\npor este estilo de gesti\u00f3n, entre ellas se encuentran 3M, General Motors,\nPepsico, MetLife, Pfizer, Xerox y la empresa mexicana Grupo Bimbo, que ha\nimplementado campa\u00f1as de prevenci\u00f3n de enfermedades graves y estacionales, de\nigual manera brinda servicios de mediciones antropom\u00e9tricas y pruebas de\ncondici\u00f3n f\u00edsica con la aplicaci\u00f3n de ex\u00e1menes m\u00e9dicos, cuenta con la\ncertificaci\u00f3n de comedores balanceados en los diferentes centros de trabajo en\nM\u00e9xico, adem\u00e1s de tener espacios destinados para activaci\u00f3n f\u00edsica dentro de\nsus instalaciones.<\/p>\n\n\n\n<p>Invertir en el bienestar de los empleados es rentable, ya que <strong>la tasa de absentismo desciende<\/strong> despu\u00e9s de la introducci\u00f3n de programas de promoci\u00f3n de la salud, los accidentes y heridas se ven reducidas y en general los <strong>costos por cuidados m\u00e9dicos<\/strong> pueden ir a la baja. <\/p>\n\n\n\n<p>Para <strong>desarrollarse como empresas saludables<\/strong> es importante contar con el acompa\u00f1amiento de profesionales que ayuden a realizar el diagn\u00f3stico adecuado, implementar las acciones necesarias y fijar objetivos a medio y largo plazo, es primordial que toda empresa cuide de su capital f\u00edsico y financiero, <strong>pero tambi\u00e9n de su capital m\u00e1s importante, el humano<\/strong>.&nbsp; <\/p>\n\n\n\n<p><strong>Referencias:<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.who.int\/es\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Organizaci\u00f3n Mundial de la Salud (opens in a new tab)\">Organizaci\u00f3n Mundial de la Salud<\/a><\/p>\n\n\n\n<p><a href=\"http:\/\/www.wwpcmex.com\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Workplace Wellness Council M\u00e9xico, Consejo Empresarial de Salud y Bienestar (opens in a new tab)\">Workplace Wellness Council M\u00e9xico, Consejo Empresarial de Salud y Bienestar<\/a><\/p>\n\n\n\n<p><a href=\"http:\/\/www.grupobimbo.com\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Grupo Bimbo (opens in a new tab)\">Grupo Bimbo<\/a><\/p>\n    \t","protected":false},"excerpt":{"rendered":"<p>Por: Ivette Rosales Herrera. \u201cLa fortaleza del equipo est\u00e1 en cada miembro por separado. La fortaleza de cada miembro es el equipo\u201d. Phil Jackson Dentro de una empresa el eslab\u00f3n m\u00e1s importante es el personal y muchas veces puede verse afectado por el estr\u00e9s laboral. Hoy en d\u00eda es muy com\u00fan escuchar que alguien sufre [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":5116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[2523,67,61],"tags":[2708,2709,2710,2711,2712,2713,2714,2715,2716,2717,2718,2719],"class_list":["post-5115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colaboracion","category-comunicacion","category-recursos-humanos","tag-absentismo-y-la-insatisfaccion-del-empleado","tag-costos-por-cuidados-medicos","tag-desarrollarse-como-empresas-saludables","tag-empresa-saludable","tag-enfermedades-relacionadas-al-trabajo","tag-estres-laboral","tag-fomentar-el-sentido-de-pertenencia","tag-la-tasa-de-absentismo-desciende","tag-la-trayectoria-de-nuestra-empresa","tag-mala-atencion-al-cliente","tag-microsoft-empresa-saludable","tag-organizaciones-saludables"],"acf":[],"featured_image_src":{"landsacpe":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables-1140x445.jpg",1140,445,true],"list":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables-463x348.jpg",463,348,true],"medium":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables-300x175.jpg",300,175,true],"full":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables.jpg",1974,1153,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cuidando el capital humano, empresas saludables - Proyectum<\/title>\n<meta name=\"description\" content=\"Por: Ivette Rosales Herrera. \u201cLa fortaleza del equipo est\u00e1 en cada miembro por separado. La fortaleza de cada miembro es el equipo\u201d. Phil Jackson Dentro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuidando el capital humano, empresas saludables - Proyectum\" \/>\n<meta property=\"og:description\" content=\"Por: Ivette Rosales Herrera. \u201cLa fortaleza del equipo est\u00e1 en cada miembro por separado. La fortaleza de cada miembro es el equipo\u201d. Phil Jackson Dentro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyectum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proyectum\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-15T18:30:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1974\" \/>\n\t<meta property=\"og:image:height\" content=\"1153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ivette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ivette\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/\"},\"author\":{\"name\":\"Ivette\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/e58ba250d0639016ae5843b1d46ff949\"},\"headline\":\"Cuidando el capital humano, empresas saludables\",\"datePublished\":\"2019-05-15T18:30:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/\"},\"wordCount\":704,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Empresas-Saludables.jpg\",\"keywords\":[\"absentismo y la insatisfacci\u00f3n del empleado\",\"costos por cuidados m\u00e9dicos\",\"desarrollarse como empresas saludables\",\"empresa saludable\",\"enfermedades relacionadas al trabajo\",\"estr\u00e9s laboral\",\"fomentar el sentido de pertenencia\",\"la tasa de absentismo desciende\",\"la trayectoria de nuestra empresa\",\"mala atenci\u00f3n al cliente\",\"Microsoft empresa saludable\",\"organizaciones saludables\"],\"articleSection\":[\"Colaboraci\u00f3n\",\"Comunicaci\u00f3n\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/\",\"name\":\"Cuidando el capital humano, empresas saludables - Proyectum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Empresas-Saludables.jpg\",\"datePublished\":\"2019-05-15T18:30:56+00:00\",\"description\":\"Por: Ivette Rosales Herrera. \u201cLa fortaleza del equipo est\u00e1 en cada miembro por separado. La fortaleza de cada miembro es el equipo\u201d. Phil Jackson Dentro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Empresas-Saludables.jpg\",\"contentUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/Empresas-Saludables.jpg\",\"width\":1974,\"height\":1153,\"caption\":\"Empresas Saludables\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/cuidando-el-capital-humano-empresas-saludables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuidando el capital humano, empresas saludables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"name\":\"Proyectum\",\"description\":\"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles\",\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\",\"name\":\"Proyectum\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"contentUrl\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"width\":600,\"height\":315,\"caption\":\"Proyectum\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proyectum\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sistemaproyectum\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCljouWimyhK_cNcC2jniUgw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/e58ba250d0639016ae5843b1d46ff949\",\"name\":\"Ivette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1c8c6ef1b741450b7436fbad6c57b987325010bbb5f25a3964446fefc0753cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1c8c6ef1b741450b7436fbad6c57b987325010bbb5f25a3964446fefc0753cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1c8c6ef1b741450b7436fbad6c57b987325010bbb5f25a3964446fefc0753cd?s=96&d=mm&r=g\",\"caption\":\"Ivette\"},\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/author\\\/ivette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuidando el capital humano, empresas saludables - Proyectum","description":"Por: Ivette Rosales Herrera. \u201cLa fortaleza del equipo est\u00e1 en cada miembro por separado. La fortaleza de cada miembro es el equipo\u201d. Phil Jackson Dentro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/","og_locale":"es_ES","og_type":"article","og_title":"Cuidando el capital humano, empresas saludables - Proyectum","og_description":"Por: Ivette Rosales Herrera. \u201cLa fortaleza del equipo est\u00e1 en cada miembro por separado. La fortaleza de cada miembro es el equipo\u201d. Phil Jackson Dentro","og_url":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/","og_site_name":"Proyectum","article_publisher":"https:\/\/www.facebook.com\/proyectum\/","article_published_time":"2019-05-15T18:30:56+00:00","og_image":[{"width":1974,"height":1153,"url":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables.jpg","type":"image\/jpeg"}],"author":"Ivette","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ivette","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/#article","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/"},"author":{"name":"Ivette","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/e58ba250d0639016ae5843b1d46ff949"},"headline":"Cuidando el capital humano, empresas saludables","datePublished":"2019-05-15T18:30:56+00:00","mainEntityOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/"},"wordCount":704,"commentCount":0,"publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/#primaryimage"},"thumbnailUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables.jpg","keywords":["absentismo y la insatisfacci\u00f3n del empleado","costos por cuidados m\u00e9dicos","desarrollarse como empresas saludables","empresa saludable","enfermedades relacionadas al trabajo","estr\u00e9s laboral","fomentar el sentido de pertenencia","la tasa de absentismo desciende","la trayectoria de nuestra empresa","mala atenci\u00f3n al cliente","Microsoft empresa saludable","organizaciones saludables"],"articleSection":["Colaboraci\u00f3n","Comunicaci\u00f3n","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/","url":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/","name":"Cuidando el capital humano, empresas saludables - Proyectum","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/#primaryimage"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/#primaryimage"},"thumbnailUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables.jpg","datePublished":"2019-05-15T18:30:56+00:00","description":"Por: Ivette Rosales Herrera. \u201cLa fortaleza del equipo est\u00e1 en cada miembro por separado. La fortaleza de cada miembro es el equipo\u201d. Phil Jackson Dentro","breadcrumb":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/#primaryimage","url":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables.jpg","contentUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2019\/05\/Empresas-Saludables.jpg","width":1974,"height":1153,"caption":"Empresas Saludables"},{"@type":"BreadcrumbList","@id":"https:\/\/proyectum.com\/sistema\/blog\/cuidando-el-capital-humano-empresas-saludables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proyectum.com\/sistema\/"},{"@type":"ListItem","position":2,"name":"Cuidando el capital humano, empresas saludables"}]},{"@type":"WebSite","@id":"https:\/\/proyectum.com\/sistema\/#website","url":"https:\/\/proyectum.com\/sistema\/","name":"Proyectum","description":"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles","publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyectum.com\/sistema\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/proyectum.com\/sistema\/#organization","name":"Proyectum","url":"https:\/\/proyectum.com\/sistema\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/","url":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","contentUrl":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","width":600,"height":315,"caption":"Proyectum"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proyectum\/","https:\/\/www.linkedin.com\/company\/sistemaproyectum\/","https:\/\/www.youtube.com\/channel\/UCljouWimyhK_cNcC2jniUgw"]},{"@type":"Person","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/e58ba250d0639016ae5843b1d46ff949","name":"Ivette","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b1c8c6ef1b741450b7436fbad6c57b987325010bbb5f25a3964446fefc0753cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1c8c6ef1b741450b7436fbad6c57b987325010bbb5f25a3964446fefc0753cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1c8c6ef1b741450b7436fbad6c57b987325010bbb5f25a3964446fefc0753cd?s=96&d=mm&r=g","caption":"Ivette"},"url":"https:\/\/proyectum.com\/sistema\/author\/ivette\/"}]}},"_links":{"self":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/5115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/comments?post=5115"}],"version-history":[{"count":0,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/5115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media\/5116"}],"wp:attachment":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media?parent=5115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/categories?post=5115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/tags?post=5115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}