{"id":603,"date":"2012-03-05T16:14:11","date_gmt":"2012-03-05T22:14:11","guid":{"rendered":"http:\/\/proyectum.wordpress.com\/?p=603"},"modified":"2012-03-05T16:14:11","modified_gmt":"2012-03-05T22:14:11","slug":"diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original","status":"publish","type":"post","link":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/","title":{"rendered":"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original"},"content":{"rendered":"<p>Quienes han trabajado y formado parte de un equipo para el desarrollo de un Proyecto, saben de las muchas cosas que pueden salir mal y, como consecuencia, impactar la fecha de terminaci\u00f3n. Por ejemplo: actividades que son m\u00e1s dif\u00edciles de lo inicialmente previsto, cambios de personal, traducidos en urgencia para preparar a los nuevos integrantes, o simple y llanamente, percatarse que muchas actividades fueron subestimadas.<\/p>\n<p>Sin importar las causas, es com\u00fan ver que un Proyecto, tiende a irse m\u00e1s all\u00e1 de la fecha l\u00edmite comprometida. Cuando el Gerente de Proyecto se percata de este hecho, su primera obligaci\u00f3n es identificar la causa. Porque si aplica remedios sin sentido, lo m\u00e1s probable es que la situaci\u00f3n se vuelva a repetir.<\/p>\n<p>\u00bfQu\u00e9 hacer despu\u00e9s de conocer la causa? \u00bfSolicitar al Cliente un cambio en la fecha de conclusi\u00f3n? Por supuesto que no. La primera obligaci\u00f3n del Gerente de Proyecto y l\u00edder del equipo, es realizar los ajustes necesarios para regresar el Proyecto al plan original. Cuando esta tendencia de ir m\u00e1s all\u00e1 de la fecha l\u00edmite se detecta al principio de un Proyecto largo, se tienen muchas opciones, si ocurre al final del mismo, las alternativas disponibles se reducen sustancialmente.<\/p>\n<p>Aqu\u00ed presentamos diez t\u00e9cnicas que aplican a distintas situaciones. Cabe mencionar que estas t\u00e9cnicas no mantienen un orden de prioridad. Todo depende de las situaciones propias de cada Proyecto, algunas aplican en un caso, mientras que otras pueden ayudar a mejorar, en otras situaciones.<\/p>\n<p><strong>Trabajar Tiempo Extra<\/strong><\/p>\n<p>A pocos o mejor dicho, a nadie le gusta, aunque una opci\u00f3n l\u00f3gica para resolver la situaci\u00f3n es, trabajar horas extra. Si la gente trabaja m\u00e1s horas al d\u00eda, avanzar\u00e1 m\u00e1s en el mismo periodo de tiempo. Las horas extra son una excelente opci\u00f3n cuando se est\u00e1 cerca del final del Proyecto y s\u00f3lo se requiere un empuj\u00f3n final para terminar a tiempo.<\/p>\n<p>Otra opci\u00f3n cuando se est\u00e1 cerca del final del Proyecto, es ofrecer el pago o compensaci\u00f3n del tiempo extra trabajado, una vez que el Proyecto est\u00e9 terminado. Cuando se est\u00e1 al principio del Proyecto, puede haber opciones m\u00e1s efectivas.<\/p>\n<p>Una factor importante son los compromisos contractuales que obligan a pagar el tiempo extra y de este modo, se afecta el presupuesto original.<\/p>\n<p><strong>Reubicar Recursos a la Ruta Cr\u00edtica<\/strong><\/p>\n<p>Una actividad b\u00e1sica del Gerente de Proyecto es identificar las actividades en crisis dentro de la Ruta Cr\u00edtica. Finalmente, si el Proyecto se observa con una tendencia de atraso, \u00e9ste lo debe reflejar la Ruta Cr\u00edtica. Una vez detectada la anomal\u00eda ser\u00e1 necesario analizar los recursos que pueden ser reubicados para reforzar las actividades en crisis. Reprogramar o extender tareas de menor urgencia, permitir\u00e1 regresar el Proyecto al cauce normal. Sin embargo se debe cuidar que los cambios en verdad ayuden a rescatar el Proyecto. Para el efecto, verifique el plan de acci\u00f3n con mayor detalle.<\/p>\n<p><strong>Verificar las Dependencias<\/strong><\/p>\n<p>Un plan de trabajo presenta el orden y la dependencia entre una actividad y otra. Por ejemplo, al construir una casa, es imposible poner la estructura si no se han terminado los cimientos, aunque, no todas las dependencias son tan dr\u00e1sticas.<\/p>\n<p>Cuando un Proyecto tiende al atraso, conviene validar las dependencias. Esta validaci\u00f3n puede exhibir: algunas actividades innecesarias, tareas planeadas para realizarse en forma secuencial, cuando se pueden ejecutar en forma paralela y, estas pueden ser la causa del retraso. En ocasiones la programaci\u00f3n del software crea, por accidente, una dependencia y cuando el Gerente del Proyecto revisa, el plan de trabajo, en una segunda instancia, se percata que tal dependencia no existe.<\/p>\n<p>Otra revisi\u00f3n importante es la que pueden hacer los integrantes del equipo, revisar el plan de acci\u00f3n para identificar dependencias que el Gerente del Proyecto pens\u00f3 como v\u00e1lidas y que en la pr\u00e1ctica pueden modificarse. Estas revisiones son muy productivas, aunque antes de realizar cualquier ajuste es conveniente verificar los datos, antes de tomar medidas dr\u00e1sticas para rescatar el Proyecto.<\/p>\n<p><strong>Revisar Actividades de Tiempo Fijo<\/strong><\/p>\n<p>Las actividades de tiempo limitado son aquellas cuya duraci\u00f3n no se altera en funci\u00f3n al n\u00famero de recursos involucrados. Por ejemplo, un curso de cinco d\u00edas al que asisten tres miembros del equipo, la duraci\u00f3n del curso no se altera aunque asistan una o diez personas.<\/p>\n<p>Este tipo de actividades deben revisarse y validar el plazo considerado. Tal vez se planearon bajo supuestos y enfoques limitados. Otros casos, una entrega prevista para tres d\u00edas puede realizarse en uno si se hace durante la noche. Se previeron dos d\u00edas para que el concreto seque, el tiempo se puede reducir usando ventiladores para agilizar el secado del concreto.<\/p>\n<p><strong>Intercambio de Recursos<\/strong><\/p>\n<p>Como ya se ha mencionado, encontrar la causa, es la primera tarea que se debe hacer cuando el Proyecto tiende a salirse del plan original. Una posible causa es la productividad de recursos que no corresponde a lo planeado. Quiz\u00e1 no tienen las habilidades y el conocimiento adecuado o no son tan productivos en este \u00e1mbito como en otras \u00e1reas. Lo m\u00e1s apropiado es buscar la forma de reemplazar estos recursos.<\/p>\n<p>En algunos casos, es suficiente reasignar a la gente a actividades distintas dentro del Proyecto. En otros casos, se puede liberar a cierto miembro del equipo y traer otro recurso. Vale la pena recordar que la clave radica en las actividades que est\u00e1n en la Ruta Cr\u00edtica. Una buena opci\u00f3n es asignar los recursos m\u00e1s productivos a estas actividades y, reasignar a los recursos menos productivos a las actividades no cr\u00edticas. Aun cuando las actividades de la Ruta Cr\u00edtica est\u00e1n retrasadas, se puede cumplir con la fecha de terminaci\u00f3n del Proyecto en general.<\/p>\n<p><strong>Replantear el Plan de Acci\u00f3n<\/strong><\/p>\n<p>Replantear el plan de trabajo implica asignar recursos adicionales a la Ruta Cr\u00edtica. Siempre es posible asignar recursos adicionales a las actividades en crisis, aunque replantear, tambi\u00e9n significa optimizar al m\u00e1ximo el plan de trabajo al menor costo.<\/p>\n<p>Por ejemplo, si se asign\u00f3 una persona para una actividad de diez d\u00edas, dos personas la podr\u00edan terminar en cinco, al estar involucrando el doble de recursos para la mitad del tiempo, puede no haber ning\u00fan costo adicional. Si dos personas terminan el trabajo en seis d\u00edas, si bien el programa se acelera, existir\u00e1 un costo adicional de dos d\u00edas de trabajo, dos personas durante seis d\u00edas frente a la estimaci\u00f3n original de diez d\u00edas.<\/p>\n<p>En el ejemplo, el plan se puede replantear con m\u00e1s agresividad, asignando tres recursos. Ahora la actividad puede tomar cuatro d\u00edas, o cuatro d\u00edas y medio. Nuestra conclusi\u00f3n, a mayores recursos involucrados en una actividad, mayor ser\u00e1 el costo y menor la productividad.<\/p>\n<p>Los recursos adicionales pueden surgir del mismo equipo, o pueden ser conseguidos temporalmente de un fuente externa. Uno de los objetivos de replantear el plan es, reducir al m\u00ednimo el costo. Sin embargo, terminar el trabajo antes de lo previsto, generalmente implica un costo adicional, si respetar la fecha l\u00edmite es m\u00e1s importante que mantener el costo, colapsar el plan puede ayudar a acelerar la conclusi\u00f3n del Proyecto.<\/p>\n<p><strong>Por la Libre<\/strong><\/p>\n<p>El Fast Track es una opci\u00f3n que implica revisar el plan de trabajo para identificar actividades previstas para ejecutarse en forma secuencial y replantearlas para realizarlas, total o parcialmente, en paralelo.<\/p>\n<p>En el caso de la construcci\u00f3n de la casa, se mencion\u00f3 que, para colocar la estructura es necesario terminar los cimientos. En una construcci\u00f3n grande, se puede montar la estructura donde los cimientos hayan sido terminados.<\/p>\n<p>Otro ejemplo com\u00fan se presenta en el dise\u00f1o y construcci\u00f3n de un sistema de c\u00f3mputo. Normalmente, no se puede empezar a programar hasta que el dise\u00f1o est\u00e9 terminado. Sin embargo, al aplicar el Fast Track, se puede empezar la programaci\u00f3n de los m\u00f3dulos cuyo dise\u00f1o sea suficientemente s\u00f3lido, sin esperar a que todo el dise\u00f1o est\u00e9 totalmente terminado.<\/p>\n<p>El Fast Track es una opci\u00f3n en la que se corre el riesgo de incrementar los costos por la realizaci\u00f3n de algunos re-procesos posteriores. En el ejemplo del sistema de c\u00f3mputo, es probable que el dise\u00f1o sufra modificaciones y est\u00e1s repercutan en m\u00f3dulos ya terminados.<\/p>\n<p><strong> Tolerancia Cero para Cambios en el Alcance<\/strong><\/p>\n<p>Muchos Proyectos tienden a salirse de control, s\u00f3lo por hacer m\u00e1s trabajo del inicialmente comprometido. Esto puede ser generado por una mala gesti\u00f3n de cambios o por trabajar en peque\u00f1os cambios que se realizan sin control. Por lo tanto, cuando se est\u00e1 en riesgo de exceder la fecha l\u00edmite, el Gerente de Proyecto debe trabajar con el Cliente y con los miembros del equipo, para garantizar que todo esfuerzo se enfoque a la realizaci\u00f3n de los productos comprometidos y evitar la realizaci\u00f3n de trabajos no previstos.<\/p>\n<p><strong> Mejorar los Procesos<\/strong><\/p>\n<p>Al buscar la causa del retraso, es com\u00fan identificar la necesidad de optimizar los procesos internos de trabajo. El Gerente del Proyecto debe solicitar la opini\u00f3n de los miembros del equipo para buscar la manera de mejorar el control interno y razonar los procesos. Por ejemplo, la reuni\u00f3n diaria para revisar el estado del Proyecto puede realizarse en forma semanal. Otra raz\u00f3n puede ser los cuellos de botella para la aprobaci\u00f3n y liberaci\u00f3n de resultados.<\/p>\n<p>Es posible identificar retrasos generados por procesos externos, entonces se deben pedir cambios, definitivos o temporales, a estos procesos. El retraso puede ser ocasionado porque la gente elabora sus evaluaciones anuales de desempe\u00f1o, si bien estas evaluaciones son importantes, quiz\u00e1 puedan hacerse una vez concluidas las actividades cr\u00edticas del Proyecto.<\/p>\n<p><strong>Negociar el Alcance del Proyecto<\/strong><\/p>\n<p>Si el Gerente del Proyecto considera que el trabajo y los productos pendientes no son fundamentales, una opci\u00f3n viable es negociar con el Cliente, la posibilidad de eliminar algunos productos. Aun cuando el trabajo restante sea trascendente para la soluci\u00f3n, esta discusi\u00f3n significa un \u00faltimo recurso. Otra opci\u00f3n para terminar el Proyecto a tiempo es, entregarlo con menor funcionalidad de la comprometida para concentrar el esfuerzo a requisitos pendientes.<br \/>\n<strong><\/strong><\/p>\n<p><strong>Resumen<\/strong><\/p>\n<p>El art\u00edculo describe diez \u00e1reas a revisar cuando un Proyecto est\u00e1 fuera de lo previsto. Sin duda, la primera opci\u00f3n es terminar un trabajo retrasado, en algunos casos, esto es perfectamente aceptable. Sin embargo, partimos de la importancia que representa cumplir en la fecha de terminaci\u00f3n prevista.<\/p>\n<p>Algunas de estas t\u00e9cnicas no requieren m\u00e1s gasto del presupuestado, por esta raz\u00f3n, deben ser las primeras a aplicar. Otras, si bien aceleran el plan de trabajo, implican mayor costo en el Proyecto. Cuando la fecha l\u00edmite es m\u00e1s importante que el costo, sugerimos aplicar las t\u00e9cnicas ya descritas.<\/p>\n<p>Si mantener la fecha l\u00edmite es tan importante como respetar el presupuesto, la opci\u00f3n m\u00e1s viable es redefinir el alcance. Generalmente a menor alcance, un Proyecto se puede terminar m\u00e1s r\u00e1pido. Una vez que se conoce la causa del problema, y la flexibilidad del presupuesto, se pueden emprender las acciones m\u00e1s viables para regresar al plan original.    \t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quienes han trabajado y formado parte de un equipo para el desarrollo de un Proyecto, saben de las muchas cosas que pueden salir mal y, como consecuencia, impactar la fecha de terminaci\u00f3n. Por ejemplo: actividades que son m\u00e1s dif\u00edciles de lo inicialmente previsto, cambios de personal, traducidos en urgencia para preparar a los nuevos integrantes, [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":3669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[57,55,61],"tags":[],"class_list":["post-603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-direccion-de-proyectos","category-liderazgo","category-recursos-humanos"],"acf":[],"featured_image_src":{"landsacpe":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado-1100x445.jpg",1100,445,true],"list":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado-463x348.jpg",463,348,true],"medium":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado-300x161.jpg",300,161,true],"full":["https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado.jpg",1100,592,false]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original - Proyectum<\/title>\n<meta name=\"description\" content=\"Quienes han trabajado y formado parte de un equipo para el desarrollo de un Proyecto, saben de las muchas cosas que pueden salir mal y, como consecuencia,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original - Proyectum\" \/>\n<meta property=\"og:description\" content=\"Quienes han trabajado y formado parte de un equipo para el desarrollo de un Proyecto, saben de las muchas cosas que pueden salir mal y, como consecuencia,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyectum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proyectum\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-03-05T22:14:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jorge Vald\u00e9s Garciatorres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Vald\u00e9s Garciatorres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/\"},\"author\":{\"name\":\"Jorge Vald\u00e9s Garciatorres\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/d31dc858cdc64bb094f97de74c958a16\"},\"headline\":\"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original\",\"datePublished\":\"2012-03-05T22:14:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/\"},\"wordCount\":1920,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/Proyecto-retrasado.jpg\",\"articleSection\":[\"Direcci\u00f3n de Proyectos\",\"Liderazgo\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/\",\"name\":\"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original - Proyectum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/Proyecto-retrasado.jpg\",\"datePublished\":\"2012-03-05T22:14:11+00:00\",\"description\":\"Quienes han trabajado y formado parte de un equipo para el desarrollo de un Proyecto, saben de las muchas cosas que pueden salir mal y, como consecuencia,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/Proyecto-retrasado.jpg\",\"contentUrl\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2012\\\/03\\\/Proyecto-retrasado.jpg\",\"width\":1100,\"height\":592,\"caption\":\"Proyecto retrasado\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"name\":\"Proyectum\",\"description\":\"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles\",\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\",\"name\":\"Proyectum\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"contentUrl\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"width\":600,\"height\":315,\"caption\":\"Proyectum\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proyectum\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sistemaproyectum\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCljouWimyhK_cNcC2jniUgw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/d31dc858cdc64bb094f97de74c958a16\",\"name\":\"Jorge Vald\u00e9s Garciatorres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g\",\"caption\":\"Jorge Vald\u00e9s Garciatorres\"},\"description\":\"Jorge es autor del libro \\\"El Camino hacia la PMO \u00c1gil\\\". Es Coautor de un modelo sist\u00e9mico para la evaluaci\u00f3n y mejora del Ecosistema Organizacional de Direcci\u00f3n de de Proyectos. Ha sido consultor, instructor y facilitador desde 2005 en temas relacionados con Estrategia, Direcci\u00f3n de Proyectos y Optimizaci\u00f3n de Procesos de Negocio. Igualmente es contador de historias y frecuentemente participa en diversos foros, compartiendo sus reflexiones. Jorge es miembro de importantes organizaciones como el PMI y el NTL Institute. Adem\u00e1s, cuenta con varias certificaciones como la de PMP, Systems Thinking, Agile Leadership, entre muchas otras.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jorgevaldex\\\/\"],\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/author\\\/jvaldex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original - Proyectum","description":"Quienes han trabajado y formado parte de un equipo para el desarrollo de un Proyecto, saben de las muchas cosas que pueden salir mal y, como consecuencia,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/","og_locale":"es_ES","og_type":"article","og_title":"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original - Proyectum","og_description":"Quienes han trabajado y formado parte de un equipo para el desarrollo de un Proyecto, saben de las muchas cosas que pueden salir mal y, como consecuencia,","og_url":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/","og_site_name":"Proyectum","article_publisher":"https:\/\/www.facebook.com\/proyectum\/","article_published_time":"2012-03-05T22:14:11+00:00","og_image":[{"width":1100,"height":592,"url":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado.jpg","type":"image\/jpeg"}],"author":"Jorge Vald\u00e9s Garciatorres","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jorge Vald\u00e9s Garciatorres","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/#article","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/"},"author":{"name":"Jorge Vald\u00e9s Garciatorres","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/d31dc858cdc64bb094f97de74c958a16"},"headline":"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original","datePublished":"2012-03-05T22:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/"},"wordCount":1920,"commentCount":0,"publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/#primaryimage"},"thumbnailUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado.jpg","articleSection":["Direcci\u00f3n de Proyectos","Liderazgo","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/","url":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/","name":"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original - Proyectum","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/#primaryimage"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/#primaryimage"},"thumbnailUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado.jpg","datePublished":"2012-03-05T22:14:11+00:00","description":"Quienes han trabajado y formado parte de un equipo para el desarrollo de un Proyecto, saben de las muchas cosas que pueden salir mal y, como consecuencia,","breadcrumb":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/#primaryimage","url":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado.jpg","contentUrl":"https:\/\/proyectum.com\/sistema\/wp-content\/uploads\/2012\/03\/Proyecto-retrasado.jpg","width":1100,"height":592,"caption":"Proyecto retrasado"},{"@type":"BreadcrumbList","@id":"https:\/\/proyectum.com\/sistema\/blog\/diez-tecnicas-para-reencauzar-un-proyecto-a-su-plan-original\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proyectum.com\/sistema\/"},{"@type":"ListItem","position":2,"name":"Diez t\u00e9cnicas para reencauzar un Proyecto a su plan original"}]},{"@type":"WebSite","@id":"https:\/\/proyectum.com\/sistema\/#website","url":"https:\/\/proyectum.com\/sistema\/","name":"Proyectum","description":"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles","publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyectum.com\/sistema\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/proyectum.com\/sistema\/#organization","name":"Proyectum","url":"https:\/\/proyectum.com\/sistema\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/","url":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","contentUrl":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","width":600,"height":315,"caption":"Proyectum"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proyectum\/","https:\/\/www.linkedin.com\/company\/sistemaproyectum\/","https:\/\/www.youtube.com\/channel\/UCljouWimyhK_cNcC2jniUgw"]},{"@type":"Person","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/d31dc858cdc64bb094f97de74c958a16","name":"Jorge Vald\u00e9s Garciatorres","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8c545fb11684f0c20963dba484f2d994a1b6fad92d26f108a8188f16c288d78?s=96&d=mm&r=g","caption":"Jorge Vald\u00e9s Garciatorres"},"description":"Jorge es autor del libro \"El Camino hacia la PMO \u00c1gil\". Es Coautor de un modelo sist\u00e9mico para la evaluaci\u00f3n y mejora del Ecosistema Organizacional de Direcci\u00f3n de de Proyectos. Ha sido consultor, instructor y facilitador desde 2005 en temas relacionados con Estrategia, Direcci\u00f3n de Proyectos y Optimizaci\u00f3n de Procesos de Negocio. Igualmente es contador de historias y frecuentemente participa en diversos foros, compartiendo sus reflexiones. Jorge es miembro de importantes organizaciones como el PMI y el NTL Institute. Adem\u00e1s, cuenta con varias certificaciones como la de PMP, Systems Thinking, Agile Leadership, entre muchas otras.","sameAs":["https:\/\/www.linkedin.com\/in\/jorgevaldex\/"],"url":"https:\/\/proyectum.com\/sistema\/author\/jvaldex\/"}]}},"_links":{"self":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/comments?post=603"}],"version-history":[{"count":0,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media\/3669"}],"wp:attachment":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media?parent=603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/categories?post=603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/tags?post=603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}