{"id":836,"date":"2013-04-01T07:50:12","date_gmt":"2013-04-01T13:50:12","guid":{"rendered":"http:\/\/proyectum.wordpress.com\/?p=836"},"modified":"2013-04-01T07:50:12","modified_gmt":"2013-04-01T13:50:12","slug":"estimar-el-tiempo-para-cuidar-nuestra-salud","status":"publish","type":"post","link":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/","title":{"rendered":"Estimar el tiempo para cuidar nuestra salud"},"content":{"rendered":"<p>Aunque la estimaci\u00f3n de tiempos es una parte fundamental para el desarrollo de un <strong>proyecto<\/strong> y existen una gran cantidad de metodolog\u00edas, procesos y herramientas para estimarlos, en muchas ocasiones \u00e9sta estimaci\u00f3n no toma en cuenta diversos factores que pueden retrasar las actividades de un <strong>proyecto<\/strong>.<\/p>\n<p>Estimar la duraci\u00f3n de las actividades, seg\u00fan el PMBOK, es el proceso  que consiste en establecer aproximadamente la cantidad de periodos de trabajo necesarios para finalizar cada actividad con los recursos estimados. El estimado de la duraci\u00f3n se elabora de manera gradual, y el proceso eval\u00faa la calidad y disponibilidad de los datos de entrada. Por ejemplo, conforme va evolucionando el trabajo de ingenier\u00eda y <strong>dise\u00f1o del proyecto<\/strong>, se dispone de datos m\u00e1s detallados y precisos, lo cual mejora la exactitud de los estimados de la duraci\u00f3n. Por lo tanto, puede suponerse que el estimado de la duraci\u00f3n ser\u00e1 cada vez m\u00e1s preciso y de mejor calidad.<\/p>\n<p>Normalmente esta estimaci\u00f3n de actividades se realiza tomando como par\u00e1metro un d\u00eda laboral de 8 horas, aunque sabemos que si descontamos los tiempos muertos como son: Los 15 minutos que se llega tarde a la oficina, el tiempo en lo que revisas tus redes sociales y tus mails, cuando vas por el caf\u00e9, cuando vas al ba\u00f1o y cuando vas a comer entre otros, el tiempo real que se labora en un d\u00eda se ve reducido considerablemente.<\/p>\n<p>Cumplir con los objetivos en la fecha establecida es la meta a la que planeamos llegar y al igual que es un error no tomar en cuenta los tiempos muertos al momento de la planeaci\u00f3n y gastar el tiempo en actividades que no corresponden al proyecto en la fase de desarrollo, tambi\u00e9n es un error volcarnos a cumplir objetivos a costa de nuestro tiempo y salud.<\/p>\n<p>El descuidar aspectos como el no comer y dormir bien, puede comenzar a derivar en problemas de salud que en un momento dado pueden manifestarse de forma grave. Cuidar de nuestra <strong>salud<\/strong> es tan importante, o m\u00e1s, como cumplir las fechas establecidas del <strong>proyecto<\/strong>. Por una parte la estimaci\u00f3n de los tiempos debe ser minuciosa para ser lo m\u00e1s exacta posible para que nuestros colaboradores no sacrifiquen su salud y por otra se debe encontrar una forma adecuada para que los tiempos muertos se vean reducidos a lo m\u00ednimo posible.<\/p>\n<p>Sobre el autor: <a href=\"http:\/\/about.me\/omargarcia\" TARGET=\"_blank\" rel=\"noopener noreferrer\">Omar Garc\u00eda<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque la estimaci\u00f3n de tiempos es una parte fundamental para el desarrollo de un proyecto y existen una gran cantidad de metodolog\u00edas, procesos y herramientas para estimarlos, en muchas ocasiones \u00e9sta estimaci\u00f3n no toma en cuenta diversos factores que pueden retrasar las actividades de un proyecto. Estimar la duraci\u00f3n de las actividades, seg\u00fan el PMBOK, [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":8258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[67,57,61],"tags":[133,118,91,138],"class_list":["post-836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion","category-direccion-de-proyectos","category-recursos-humanos","tag-dia-mundial-de-la-salud","tag-lider-de-proyecto","tag-proyecto","tag-salud"],"acf":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estimar el tiempo para cuidar nuestra salud - Proyectum<\/title>\n<meta name=\"description\" content=\"Aunque la estimaci\u00f3n de tiempos es una parte fundamental para el desarrollo de un proyecto y existen una gran cantidad de metodolog\u00edas, procesos y\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estimar el tiempo para cuidar nuestra salud - Proyectum\" \/>\n<meta property=\"og:description\" content=\"Aunque la estimaci\u00f3n de tiempos es una parte fundamental para el desarrollo de un proyecto y existen una gran cantidad de metodolog\u00edas, procesos y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Proyectum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proyectum\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-01T13:50:12+00:00\" \/>\n<meta name=\"author\" content=\"Omar Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@omarzgarcia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Omar Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/\"},\"author\":{\"name\":\"Omar Garc\u00eda\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/2c2f3285c31a3a005b11add8832ae8f7\"},\"headline\":\"Estimar el tiempo para cuidar nuestra salud\",\"datePublished\":\"2013-04-01T13:50:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/\"},\"wordCount\":421,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"D\u00eda mundial de la salud\",\"l\u00edder de proyecto\",\"proyecto\",\"salud\"],\"articleSection\":[\"Comunicaci\u00f3n\",\"Direcci\u00f3n de Proyectos\",\"Recursos Humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/\",\"name\":\"Estimar el tiempo para cuidar nuestra salud - Proyectum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2013-04-01T13:50:12+00:00\",\"description\":\"Aunque la estimaci\u00f3n de tiempos es una parte fundamental para el desarrollo de un proyecto y existen una gran cantidad de metodolog\u00edas, procesos y\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/blog\\\/estimar-el-tiempo-para-cuidar-nuestra-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estimar el tiempo para cuidar nuestra salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#website\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"name\":\"Proyectum\",\"description\":\"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles\",\"publisher\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#organization\",\"name\":\"Proyectum\",\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"contentUrl\":\"https:\\\/\\\/www.proyectum.com\\\/sistema\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/proyectum-logo-snippet.png\",\"width\":600,\"height\":315,\"caption\":\"Proyectum\"},\"image\":{\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/proyectum\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sistemaproyectum\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCljouWimyhK_cNcC2jniUgw\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/#\\\/schema\\\/person\\\/2c2f3285c31a3a005b11add8832ae8f7\",\"name\":\"Omar Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g\",\"caption\":\"Omar Garc\u00eda\"},\"description\":\"Creador de contenidos en Proyectum. Para seguir la conversaci\u00f3n puedes escribirme en: @omarzgarcia\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/@omarzgarcia\"],\"url\":\"https:\\\/\\\/proyectum.com\\\/sistema\\\/author\\\/omarzgarcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estimar el tiempo para cuidar nuestra salud - Proyectum","description":"Aunque la estimaci\u00f3n de tiempos es una parte fundamental para el desarrollo de un proyecto y existen una gran cantidad de metodolog\u00edas, procesos y","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/","og_locale":"es_ES","og_type":"article","og_title":"Estimar el tiempo para cuidar nuestra salud - Proyectum","og_description":"Aunque la estimaci\u00f3n de tiempos es una parte fundamental para el desarrollo de un proyecto y existen una gran cantidad de metodolog\u00edas, procesos y","og_url":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/","og_site_name":"Proyectum","article_publisher":"https:\/\/www.facebook.com\/proyectum\/","article_published_time":"2013-04-01T13:50:12+00:00","author":"Omar Garc\u00eda","twitter_card":"summary_large_image","twitter_creator":"@omarzgarcia","twitter_misc":{"Escrito por":"Omar Garc\u00eda","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/#article","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/"},"author":{"name":"Omar Garc\u00eda","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/2c2f3285c31a3a005b11add8832ae8f7"},"headline":"Estimar el tiempo para cuidar nuestra salud","datePublished":"2013-04-01T13:50:12+00:00","mainEntityOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/"},"wordCount":421,"commentCount":0,"publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/#primaryimage"},"thumbnailUrl":"","keywords":["D\u00eda mundial de la salud","l\u00edder de proyecto","proyecto","salud"],"articleSection":["Comunicaci\u00f3n","Direcci\u00f3n de Proyectos","Recursos Humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/","url":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/","name":"Estimar el tiempo para cuidar nuestra salud - Proyectum","isPartOf":{"@id":"https:\/\/proyectum.com\/sistema\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/#primaryimage"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/#primaryimage"},"thumbnailUrl":"","datePublished":"2013-04-01T13:50:12+00:00","description":"Aunque la estimaci\u00f3n de tiempos es una parte fundamental para el desarrollo de un proyecto y existen una gran cantidad de metodolog\u00edas, procesos y","breadcrumb":{"@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/proyectum.com\/sistema\/blog\/estimar-el-tiempo-para-cuidar-nuestra-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/proyectum.com\/sistema\/"},{"@type":"ListItem","position":2,"name":"Estimar el tiempo para cuidar nuestra salud"}]},{"@type":"WebSite","@id":"https:\/\/proyectum.com\/sistema\/#website","url":"https:\/\/proyectum.com\/sistema\/","name":"Proyectum","description":"Direcci\u00f3n de Proyectos y M\u00e9todos \u00c1giles","publisher":{"@id":"https:\/\/proyectum.com\/sistema\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proyectum.com\/sistema\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/proyectum.com\/sistema\/#organization","name":"Proyectum","url":"https:\/\/proyectum.com\/sistema\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/","url":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","contentUrl":"https:\/\/www.proyectum.com\/sistema\/wp-content\/uploads\/2020\/04\/proyectum-logo-snippet.png","width":600,"height":315,"caption":"Proyectum"},"image":{"@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/proyectum\/","https:\/\/www.linkedin.com\/company\/sistemaproyectum\/","https:\/\/www.youtube.com\/channel\/UCljouWimyhK_cNcC2jniUgw"]},{"@type":"Person","@id":"https:\/\/proyectum.com\/sistema\/#\/schema\/person\/2c2f3285c31a3a005b11add8832ae8f7","name":"Omar Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6287ae96abd3e19dcc272b2c1ff8c5c0a0fcf3149e67894ce1b778f4232770a9?s=96&d=mm&r=g","caption":"Omar Garc\u00eda"},"description":"Creador de contenidos en Proyectum. Para seguir la conversaci\u00f3n puedes escribirme en: @omarzgarcia","sameAs":["https:\/\/x.com\/@omarzgarcia"],"url":"https:\/\/proyectum.com\/sistema\/author\/omarzgarcia\/"}]}},"_links":{"self":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":0,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/posts\/836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proyectum.com\/sistema\/wp-json\/wp\/v2\/tags?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}